{"id":17,"count":18,"description":"","link":"https:\/\/tristel.com\/fr-fr\/latest-news\/disciplines\/oto-rhino-laryngologie\/","name":"Oto-rhino-laryngologie","slug":"oto-rhino-laryngologie","taxonomy":"discipline","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/tristel.com\/fr-fr\/wp-json\/wp\/v2\/discipline\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tristel.com\/fr-fr\/wp-json\/wp\/v2\/discipline"}],"about":[{"href":"https:\/\/tristel.com\/fr-fr\/wp-json\/wp\/v2\/taxonomies\/discipline"}],"wp:post_type":[{"href":"https:\/\/tristel.com\/fr-fr\/wp-json\/wp\/v2\/posts?discipline=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}