{"id":10445,"date":"2026-05-27T07:01:33","date_gmt":"2026-05-27T06:01:33","guid":{"rendered":"https:\/\/tristel.com\/de-de\/latest-news\/\/"},"modified":"2026-07-10T08:38:15","modified_gmt":"2026-07-10T07:38:15","slug":"unter-dem-mikroskop-hantavirus","status":"publish","type":"post","link":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/","title":{"rendered":"Unter dem Mikroskop: Hantavirus"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/tristel.com\/wp-content\/uploads\/2026\/05\/hantavirus_blog-1024x627-1-992x607.jpg\" alt=\"Illustration of enveloped hantavirus particles showing the spherical viral structure against a blue background.\" class=\"wp-image-41422\" style=\"object-fit:cover;width:900px;height:270px\" \/><\/figure>\n\n\n\n<p class=\"has-h-4-font-size wp-block-paragraph\">Hantaviren sind seltene, jedoch potenziell schwerwiegende zoonotische Erreger, die schwere respiratorische oder renale Krankheitsverl\u00e4ufe ausl\u00f6sen k\u00f6nnen. Obwohl Infektionen insgesamt selten sind, haben aktuelle Berichte \u00fcber einen Ausbruch im Zusammenhang mit einem Kreuzfahrtschiff, der mit dem Andes-Virus in Verbindung steht, das Interesse von Gesundheitsbeh\u00f6rden und Fachkreisen erneut verst\u00e4rkt.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-4506e9c9eb0dc4660bd1187bd577b402\" id=\"h-was-sind-hantaviren\">Was sind Hantaviren?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hantaviren sind eine Gruppe von beh\u00fcllten RNA\u2011Viren aus der Familie der <em>Hantaviridae<\/em>. Es handelt sich um zoonotische Erreger, die vom Tier auf den Menschen \u00fcbertragen werden k\u00f6nnen und weltweit als Ursache schwerer Erkrankungen der Atemwege und der Nieren gelten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infektionen mit Hantaviren sind weltweit vergleichsweise selten, k\u00f6nnen jedoch schwer verlaufen. Unterschiedliche Hantavirus-Arten sind mit jeweils spezifischen Krankheitsbildern verbunden.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"wp-block-paragraph\"><strong>Wussten Sie schon?<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach Sch\u00e4tzungen der WHO kommt es j\u00e4hrlich weltweit zu 10.000 bis \u00fcber 100.000 Hantavirus-Infektionen, mit den h\u00f6chsten Fallzahlen in Asien und Europa.<\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-b41569ccbaa2c4355d713ee82c6fc676\" id=\"h-wo-kommen-hantaviren-vor\">Wo kommen Hantaviren vor?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hantaviren werden nat\u00fcrlicherweise von Nagetieren getragen, die als Hauptreservoir dienen. Das Virus wird \u00fcber Urin, Kot und Speichel der Tiere ausgeschieden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Ansteckung des Menschen erfolgt meist, wenn:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Oberfl\u00e4chen oder Gegenst\u00e4nde ber\u00fchrt werden, die mit Ausscheidungen von Nagetieren kontaminiert sind, und anschlie\u00dfend Mund, Nase oder Augen ber\u00fchrt werden<\/li>\n\n\n\n<li>Staub eingeatmet wird, der mit Urin oder Kot infizierter Nagetiere belastet ist<\/li>\n\n\n\n<li>geschlossene oder schlecht bel\u00fcftete R\u00e4ume betreten werden, in denen sich Nagetiere aufhalten<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"wp-block-paragraph\"><strong>Wussten Sie schon?<\/strong> <br \/>Bereiche wie H\u00fctten, Lagerr\u00e4ume, Technikr\u00e4ume, Bereiche zur Lebensmittelverarbeitung und selten genutzte R\u00e4ume stellen ein erh\u00f6htes Risiko <br \/>dar, wenn dort Nagetierbefall vorliegt.<\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-42757ce8959bf3c6387439ddcab1c26d\" id=\"h-hantavirus-krankheitsbilder-und-auswirkungen\">Hantavirus: Krankheitsbilder und Auswirkungen?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"h-what-do-hantaviruses-cause\">Fr\u00fche Symptome einer Hantavirus-Infektion sind oft unspezifisch und k\u00f6nnen folgende Anzeichen umfassen:<\/p>\n\n\n\n<div class=\"wp-block-group\">\n<ul class=\"wp-block-list\">\n<li>Fieber, M\u00fcdigkeit und Muskelschmerzen<\/li>\n\n\n\n<li>Kopfschmerzen, \u00dcbelkeit, Erbrechen und Bauchschmerzen<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/tristel.com\/wp-content\/uploads\/2026\/05\/AdobeStock_225041107-992x558.jpeg\" alt=\"\" class=\"wp-image-41465\" style=\"object-fit:cover;width:auto;height:200px\" \/><\/figure>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In schwereren F\u00e4llen kann sich die Infektion weiterentwickeln zu:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Hantavirus-pulmonales Syndrom (HPS)<\/strong>, mit rasch einsetzenden Atembeschwerden bis hin zum Atemversagen<\/li>\n\n\n\n<li><strong>H\u00e4morrhagischem Fieber mit renalem Syndrom (HFRS)<\/strong>, das mit Nierenfunktionsst\u00f6rungen und Blutungskomplikationen einhergeht<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"h-what-do-hantaviruses-cause\">Bei Verdacht auf eine Infektion ist eine zeitnahe medizinische Abkl\u00e4rung entscheidend.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-9770174e6a5147d69de740e779b9da82\" id=\"h-wie-wird-das-hantavirus-ubertragen\">Wie wird das Hantavirus \u00fcbertragen?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Einatmen von Aerosolen, die mit Urin, Kot oder Speichel von Nagetieren kontaminiert sind<\/li>\n\n\n\n<li>Direkter Kontakt mit kontaminierten Materialien, gefolgt vom Ber\u00fchren von Mund, Nase oder Augen<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Im Gegensatz zu vielen anderen Atemwegsviren ist eine \u00dcbertragung von Mensch zu Mensch bei den meisten Hantavirus-Arten \u00e4u\u00dferst selten.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-f7837428c3c5ca015a614a91a88b276d\" id=\"h-warum-stellt-das-hantavirus-derzeit-kein-relevantes-risiko-fur-krankenhauser-dar\">Warum stellt das Hantavirus derzeit kein relevantes Risiko f\u00fcr Krankenh\u00e4user dar?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hantaviren gelten nicht als typische nosokomiale Infektion, da:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>die \u00dcbertragung in der Regel \u00fcber die Umwelt erfolgt und nicht von Patient zu Patient<\/li>\n\n\n\n<li>der Kontakt mit Nagetieren den wichtigsten Risikofaktor darstellt<\/li>\n\n\n\n<li>eine anhaltende \u00dcbertragung von Mensch zu Mensch in Gesundheitseinrichtungen bislang nicht beobachtet wurde<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ausbr\u00fcche sind selten und stehen, wenn sie auftreten, meist im Zusammenhang mit spezifischen Umweltfaktoren und nicht mit M\u00e4ngeln in der Infektionspr\u00e4vention im klinischen Umfeld.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-633948101d10c4b0932ff74c70766400\" id=\"h-aktuelle-ereignisse-das-andes-virus\">Aktuelle Ereignisse: das Andes-Virus<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gesundheitsbeh\u00f6rden zufolge steht der Ausbruch im Umfeld eines Kreuzfahrtschiffs im Zusammenhang mit dem Andes-Virus, einer Virusvariante aus der Familie <em>Hantaviridae<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Andes-Virus ist aus folgenden Gr\u00fcnden besonders relevant:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Es handelt sich, wie andere Vertreter der Familie <em>Hantaviridae<\/em>, um ein beh\u00fclltes Hantavirus<\/li>\n\n\n\n<li>Es wird mit dem Hantavirus\u2011pulmonalen Syndrom (HPS) in Verbindung gebracht<\/li>\n\n\n\n<li>Im Gegensatz zu den meisten Hantaviren wurden in seltenen F\u00e4llen begrenzte \u00dcbertragungen von Mensch zu Mensch dokumentiert, in der Regel bei l\u00e4ngerem engen Kontakt und vor allem in fr\u00fchen Krankheitsphasen<\/li>\n\n\n\n<li>Die Inkubationszeit ist vergleichsweise lang und kann bis zu etwa 18 Tage betragen<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"wp-block-paragraph\"><strong>Wussten Sie schon?<\/strong> <br \/>Auch beim Andes-Virus bleibt die Exposition gegen\u00fcber Ausscheidungen von Nagetieren der wichtigste \u00dcbertragungsweg, w\u00e4hrend eine \u00dcbertragung von Mensch zu Mensch selten ist. Aus Sicht der Infektionspr\u00e4vention und -kontrolle ver\u00e4ndert diese Virusvariante die grundlegenden Prinzipien nicht, unterstreicht jedoch die Bedeutung von Hygiene in der Umgebung sowie eines fr\u00fchzeitigen Risikomanagements, insbesondere in gemeinsam genutzten oder geschlossenen R\u00e4umen.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-e0c8c9eacc351ca979d7afb0d0e15815\" id=\"h-warum-stellen-hantaviren-ein-mikrobielles-risiko-dar\">Warum stellen Hantaviren ein mikrobielles Risiko dar?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hantaviren stellen aus mehreren Gr\u00fcnden ein relevantes Risiko f\u00fcr die \u00f6ffentliche Gesundheit dar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Schwere Krankheitsverl\u00e4ufe k\u00f6nnen sich rasch entwickeln<\/li>\n\n\n\n<li>Unspezifische Fr\u00fchsymptome k\u00f6nnen die Diagnosestellung verz\u00f6gern<\/li>\n\n\n\n<li>Nagetier-Reservoire sind weit verbreitet und nur schwer zu kontrollieren<\/li>\n\n\n\n<li>Exposition kann im privaten Umfeld, am Arbeitsplatz sowie in Reise- und Gastgewerbe-Umgebungen erfolgen<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"wp-block-paragraph\"><strong>Wussten Sie schon?<\/strong> <br \/>Ausbr\u00fcche sind selten, machen jedoch deutlich, wie wichtig gezielte Ma\u00dfnahmen zur Risikoreduktion in der Umgebung sowie konsequente Hygienepraktiken sind.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-6f639b7af1e8d762d099e0a9a54b862d\" id=\"h-wie-lasst-sich-die-ausbreitung-von-hantaviren-verhindern\">Wie l\u00e4sst sich die Ausbreitung von Hantaviren verhindern?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Zentrale Pr\u00e4ventionsma\u00dfnahmen, die von Gesundheitsbeh\u00f6rden empfohlen werden, umfassen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Effektive Ma\u00dfnahmen zur Bek\u00e4mpfung und Fernhaltung von Nagetieren<\/li>\n\n\n\n<li>Verzicht auf trockenes Kehren oder Staubsaugen in Bereichen, die mit Nagetierkot oder -urin kontaminiert sein k\u00f6nnten<\/li>\n\n\n\n<li>Einsatz feuchter Reinigungs- und Desinfektionsmethoden, um die Bildung von Aerosolen zu minimieren<\/li>\n\n\n\n<li>Tragen geeigneter pers\u00f6nlicher Schutzausr\u00fcstung (PSA) bei der Reinigung potenziell kontaminierter Bereiche<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reinigung und Desinfektion von R\u00e4umlichkeiten tragen wesentlich dazu bei, das Risiko einer indirekten Exposition zu reduzieren.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-ffdc3e4dde6a5ea6904832a7ab68940d\" id=\"h-wie-kann-man-sich-gegen-hantaviren-schutzen\"><strong>Wie kann man sich gegen Hantaviren sch\u00fctzen?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Als beh\u00fcllte Viren geh\u00f6ren Hantaviren \u2013 einschlie\u00dflich des Andes-Virus \u2013 zu den weniger widerstandsf\u00e4higen Viren gegen\u00fcber Desinfektionsma\u00dfnahmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desinfektionsmittel mit nachgewiesener viruzider Wirksamkeit sind bei Anwendung gem\u00e4\u00df validierten Standards und Einwirkzeiten voraussichtlich wirksam gegen Hantaviren. Zu den relevanten Normen z\u00e4hlt unter anderem die EN 14476.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Breit wirksame Desinfektionsmittel, wie beispielsweise Produkte auf Basis von Chlordioxid, bieten Schutz gegen\u00fcber einem breiten Spektrum an Erregern \u2013 nicht nur Viren, sondern auch Bakterien, Mykobakterien, Pilzen und bakteriellen Sporen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"wp-block-paragraph\"><strong>Wussten Sie schon? <\/strong><br \/>Der Einsatz eines breit wirksamen Desinfektionsmittels tr\u00e4gt dazu bei, eine effektive Infektionspr\u00e4vention und -kontrolle in R\u00e4umlichkeiten sicherzustellen, in denen mehrere mikrobielle Risiken gleichzeitig auftreten k\u00f6nnen.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading has-purple-color has-text-color has-link-color wp-elements-339b30bf1c36ffac18823a381b866ec0\" id=\"h-wirkstoffe-konzentrationen-und-die-bedeutung-von-en-normen\">Wirkstoffe, Konzentrationen und die Bedeutung von EN-Normen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Leitlinien zur Desinfektion w\u00e4hrend Ausbr\u00fcchen beziehen sich h\u00e4ufig auf chlorbasierte Produkte und Konzentrationsangaben in parts per million (ppm), beispielsweise 1.000 ppm oder 10.000 ppm. Die Konzentration allein entscheidet jedoch nicht dar\u00fcber, ob ein Desinfektionsmittel wirksam ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die EN 14885 beschreibt die Normen, die in Europa zur Bewertung der bioziden Wirksamkeit von chemischen Desinfektionsmitteln und Antiseptika herangezogen werden. Sie bietet einen Rahmen zur Beurteilung der Desinfektionsleistung und erm\u00f6glicht es Herstellern, Anwendern und zust\u00e4ndigen Beh\u00f6rden, Produktangaben auf Basis standardisierter und reproduzierbarer Wirksamkeitspr\u00fcfungen zu bewerten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Wirksamkeitspr\u00fcfung nach EN 14885 ber\u00fccksichtigt verschiedene Faktoren, die die Leistung von Desinfektionsmitteln beeinflussen, darunter die Konzentration des Wirkstoffs, die Einwirkzeit, die Oberfl\u00e4chenbeschaffenheit sowie das Vorhandensein organischer Belastungen. Da Desinfektionsmittel unterschiedliche Wirkstoffe enthalten und verschiedenen Wirkmechanismen folgen, lassen sich ppm-Empfehlungen nicht pauschal auf alle Produktarten \u00fcbertragen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"wp-block-paragraph\"><strong>Wussten Sie schon?<\/strong><em>&nbsp;<\/em><br \/>Empfehlungen wie \u201e1.000 ppm\u201c oder \u201e10.000 ppm\u201c lassen sich nicht allgemeing\u00fcltig auf alle Desinfektionsmittel \u00fcbertragen. Die tats\u00e4chliche Wirksamkeit h\u00e4ngt vom Wirkstoff, seinem Wirkmechanismus und der Art der Pr\u00fcfung ab, weshalb validierte EN-Daten eine zentrale Rolle spielen.<\/p>\n<\/blockquote>\n\n\n<div class=\"tristel-products gutenberg wp-block-create-block-tristel-products\"><div class=\"tristel-products__grid\"><a class=\"product-card\" href=\"https:\/\/tristel.com\/de-de\/product\/tristel-fuse-for-medical-surfaces\/\">\n\t<div class=\"product-card__image-wrap\">\n\t\t<img decoding=\"async\" width=\"576\" height=\"425\" src=\"https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-576x425.jpg\" class=\"product-card__image\" alt=\"\" srcset=\"https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-576x425.jpg 576w, https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-768x566.jpg 768w, https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-992x732.jpg 992w, https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-320x236.jpg 320w, https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-1200x885.jpg 1200w, https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-1400x1032.jpg 1400w, https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-1600x1180.jpg 1600w, https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-1920x1416.jpg 1920w, https:\/\/tristel.com\/de-de\/wp-content\/uploads\/sites\/36\/2024\/11\/Tristel-Fuse-for-Medical-Surfaces-Box-and-Sachet-scaled.jpg 2048w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/>\t\t\t<\/div>\n\t<article class=\"product-card__article\">\n\t\t<h6 class=\"product-card__headline\">Fuse for Medical Surfaces<\/h6>\n\t\t<span class=\"product-card__hover-effect hover-effect\"\n\t\t\t  style=\"background-color:#0d5d3e\"><\/span>\n\t<\/article>\n<\/a>\n\n\n\n<\/div><\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-default\" \/>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>Quellen:<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><br \/>Public Health England (2008). <em>Hantaviruses<\/em>. [online] GOV.UK. Available at: https:\/\/www.gov.uk\/guidance\/hantaviruses.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">UK Health Security Agency (2026). <em>What Is hantavirus? How Is It Transmitted and What Are the symptoms? \u2013 UK Health Security Agency<\/em>. [online] Blog.gov.uk. Available at: https:\/\/ukhsa.blog.gov.uk\/2026\/05\/05\/what-is-hantavirus-how-is-it-transmitted-and-what-are-the-symptoms\/. <\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">WHO (2026). <em>Detail &#8211; Hantavirus<\/em>. [online] Who.int. Available at: https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/hantavirus.Clinic, C. (2019). <\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">CDC (2024). <em>About hantavirus<\/em>. [online] Hantavirus. Available at: https:\/\/www.cdc.gov\/hantavirus\/about\/index.html.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">England, N. (2026).&nbsp;<em>NHS England\u00bb Infection prevention and control measures for asymptomatic contacts, clinically suspected, and confirmed cases of Andes virus (hantavirus) in healthcare settings<\/em>. [online]&nbsp;England.nhs.uk. Available at:&nbsp;<a href=\"https:\/\/www.england.nhs.uk\/long-read\/ipc-measures-asymptomatic-contacts-cases-hantavirus-healthcare-settings\/\">https:\/\/www.england.nhs.uk\/long-read\/ipc-measures-asymptomatic-contacts-cases-hantavirus-healthcare-settings\/<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hantaviren sind seltene, jedoch potenziell schwerwiegende zoonotische Erreger, die schwere respiratorische oder renale Krankheitsverl\u00e4ufe ausl\u00f6sen k\u00f6nnen. Obwohl Infektionen insgesamt selten sind, haben aktuelle Berichte \u00fcber einen Ausbruch im Zusammenhang mit [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":10467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"footnotes":""},"categories":[76],"tags":[],"media_type":[5],"portfolio":[13,12],"discipline":[],"class_list":["post-10445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unter-dem-mikroskop","media_type-blog","portfolio-cache","portfolio-tristel"],"acf":[],"featured_media_global":{"id":41422,"title":{"rendered":"hantavirus_blog-1024x627"},"description":{"rendered":""},"caption":{"rendered":""},"alt_text":"Illustration of enveloped hantavirus particles showing the spherical viral structure against a blue background.","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":627,"file":"2026\/05\/hantavirus_blog-1024x627-1.jpg","filesize":160344,"sizes":{"medium":{"file":"hantavirus_blog-1024x627-1-768x470.jpg","width":768,"height":470,"mime-type":"image\/jpeg","filesize":93450},"large":{"file":"hantavirus_blog-1024x627-1-992x607.jpg","width":992,"height":607,"mime-type":"image\/jpeg","filesize":137574},"thumbnail":{"file":"hantavirus_blog-1024x627-1-320x320.jpg","width":320,"height":320,"mime-type":"image\/jpeg","filesize":34917},"xsmall":{"file":"hantavirus_blog-1024x627-1-320x196.jpg","width":320,"height":196,"mime-type":"image\/jpeg","filesize":22597},"small":{"file":"hantavirus_blog-1024x627-1-576x353.jpg","width":576,"height":353,"mime-type":"image\/jpeg","filesize":59120}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"source_url":"https:\/\/tristel.com\/wp-content\/uploads\/2026\/05\/hantavirus_blog-1024x627-1.jpg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Unter dem Mikroskop: Hantavirus<\/title>\n<meta name=\"description\" content=\"Erfahren Sie, wie Hantaviren \u00fcbertragen werden, welche Risiken bestehen und welche Ma\u00dfnahmen zur Pr\u00e4vention und Desinfektion wirksam sind.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unter dem Mikroskop: Hantavirus\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie, wie Hantaviren \u00fcbertragen werden, welche Risiken bestehen und welche Ma\u00dfnahmen zur Pr\u00e4vention und Desinfektion wirksam sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Tristel - Germany - DE\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-27T06:01:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T07:38:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tristel.com\/wp-content\/uploads\/2026\/05\/hantavirus_blog-1024x627-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sabinejanz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabinejanz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/\"},\"author\":{\"name\":\"sabinejanz\",\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/#\\\/schema\\\/person\\\/62a2fd8105ee192c68c233235966378e\"},\"headline\":\"Unter dem Mikroskop: Hantavirus\",\"datePublished\":\"2026-05-27T06:01:33+00:00\",\"dateModified\":\"2026-07-10T07:38:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/\"},\"wordCount\":1237,\"image\":{\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tristel.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/hantavirus_blog-1024x627-1.jpg\",\"articleSection\":[\"Unter dem Mikroskop\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/\",\"url\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/\",\"name\":\"Unter dem Mikroskop: Hantavirus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tristel.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/hantavirus_blog-1024x627-1.jpg\",\"datePublished\":\"2026-05-27T06:01:33+00:00\",\"dateModified\":\"2026-07-10T07:38:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/#\\\/schema\\\/person\\\/62a2fd8105ee192c68c233235966378e\"},\"description\":\"Erfahren Sie, wie Hantaviren \u00fcbertragen werden, welche Risiken bestehen und welche Ma\u00dfnahmen zur Pr\u00e4vention und Desinfektion wirksam sind.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tristel.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/hantavirus_blog-1024x627-1.jpg\",\"contentUrl\":\"https:\\\/\\\/tristel.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/hantavirus_blog-1024x627-1.jpg\",\"caption\":\"Illustration of enveloped hantavirus particles showing the spherical viral structure against a blue background.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/latest-news\\\/unter-dem-mikroskop-hantavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unter dem Mikroskop: Hantavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/\",\"name\":\"Tristel\",\"description\":\"Die Chemie stimmt\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/#\\\/schema\\\/person\\\/62a2fd8105ee192c68c233235966378e\",\"name\":\"sabinejanz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76c2c2485d275b209bbf41b5fc9a764cc8180fb0b726a3707b2714d4a6053275?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76c2c2485d275b209bbf41b5fc9a764cc8180fb0b726a3707b2714d4a6053275?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76c2c2485d275b209bbf41b5fc9a764cc8180fb0b726a3707b2714d4a6053275?s=96&d=mm&r=g\",\"caption\":\"sabinejanz\"},\"url\":\"https:\\\/\\\/tristel.com\\\/de-de\\\/author\\\/sabinejanz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Unter dem Mikroskop: Hantavirus","description":"Erfahren Sie, wie Hantaviren \u00fcbertragen werden, welche Risiken bestehen und welche Ma\u00dfnahmen zur Pr\u00e4vention und Desinfektion wirksam sind.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/","og_locale":"en_GB","og_type":"article","og_title":"Unter dem Mikroskop: Hantavirus","og_description":"Erfahren Sie, wie Hantaviren \u00fcbertragen werden, welche Risiken bestehen und welche Ma\u00dfnahmen zur Pr\u00e4vention und Desinfektion wirksam sind.","og_url":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/","og_site_name":"Tristel - Germany - DE","article_published_time":"2026-05-27T06:01:33+00:00","article_modified_time":"2026-07-10T07:38:15+00:00","og_image":[{"url":"https:\/\/tristel.com\/wp-content\/uploads\/2026\/05\/hantavirus_blog-1024x627-1.jpg","width":1024,"height":627,"type":"image\/jpeg"}],"author":"sabinejanz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sabinejanz","Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/#article","isPartOf":{"@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/"},"author":{"name":"sabinejanz","@id":"https:\/\/tristel.com\/de-de\/#\/schema\/person\/62a2fd8105ee192c68c233235966378e"},"headline":"Unter dem Mikroskop: Hantavirus","datePublished":"2026-05-27T06:01:33+00:00","dateModified":"2026-07-10T07:38:15+00:00","mainEntityOfPage":{"@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/"},"wordCount":1237,"image":{"@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/tristel.com\/wp-content\/uploads\/2026\/05\/hantavirus_blog-1024x627-1.jpg","articleSection":["Unter dem Mikroskop"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/","url":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/","name":"Unter dem Mikroskop: Hantavirus","isPartOf":{"@id":"https:\/\/tristel.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/#primaryimage"},"image":{"@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/tristel.com\/wp-content\/uploads\/2026\/05\/hantavirus_blog-1024x627-1.jpg","datePublished":"2026-05-27T06:01:33+00:00","dateModified":"2026-07-10T07:38:15+00:00","author":{"@id":"https:\/\/tristel.com\/de-de\/#\/schema\/person\/62a2fd8105ee192c68c233235966378e"},"description":"Erfahren Sie, wie Hantaviren \u00fcbertragen werden, welche Risiken bestehen und welche Ma\u00dfnahmen zur Pr\u00e4vention und Desinfektion wirksam sind.","breadcrumb":{"@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/#primaryimage","url":"https:\/\/tristel.com\/wp-content\/uploads\/2026\/05\/hantavirus_blog-1024x627-1.jpg","contentUrl":"https:\/\/tristel.com\/wp-content\/uploads\/2026\/05\/hantavirus_blog-1024x627-1.jpg","caption":"Illustration of enveloped hantavirus particles showing the spherical viral structure against a blue background."},{"@type":"BreadcrumbList","@id":"https:\/\/tristel.com\/de-de\/latest-news\/unter-dem-mikroskop-hantavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tristel.com\/de-de\/"},{"@type":"ListItem","position":2,"name":"Unter dem Mikroskop: Hantavirus"}]},{"@type":"WebSite","@id":"https:\/\/tristel.com\/de-de\/#website","url":"https:\/\/tristel.com\/de-de\/","name":"Tristel","description":"Die Chemie stimmt","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tristel.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/tristel.com\/de-de\/#\/schema\/person\/62a2fd8105ee192c68c233235966378e","name":"sabinejanz","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/76c2c2485d275b209bbf41b5fc9a764cc8180fb0b726a3707b2714d4a6053275?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/76c2c2485d275b209bbf41b5fc9a764cc8180fb0b726a3707b2714d4a6053275?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76c2c2485d275b209bbf41b5fc9a764cc8180fb0b726a3707b2714d4a6053275?s=96&d=mm&r=g","caption":"sabinejanz"},"url":"https:\/\/tristel.com\/de-de\/author\/sabinejanz\/"}]}},"_links":{"self":[{"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/posts\/10445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/comments?post=10445"}],"version-history":[{"count":0,"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/posts\/10445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/media\/10467"}],"wp:attachment":[{"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/media?parent=10445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/categories?post=10445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/tags?post=10445"},{"taxonomy":"media_type","embeddable":true,"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/media_type?post=10445"},{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/portfolio?post=10445"},{"taxonomy":"discipline","embeddable":true,"href":"https:\/\/tristel.com\/de-de\/wp-json\/wp\/v2\/discipline?post=10445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}